{"id":200,"date":"2011-05-05T16:47:42","date_gmt":"2011-05-05T18:47:42","guid":{"rendered":"http:\/\/www.encontrapraiagrande.com.br\/noticias\/?p=200"},"modified":"2013-08-14T13:05:11","modified_gmt":"2013-08-14T15:05:11","slug":"homem-atira-e-fere-duas-pessoas-em-praia-grande","status":"publish","type":"post","link":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/homem-atira-e-fere-duas-pessoas-em-praia-grande\/","title":{"rendered":"Homem atira e fere duas pessoas em Praia Grande"},"content":{"rendered":"<p>Um homem que estava em uma motocicleta atirou e feriu duas pessoas na tarde de ter\u00e7a-feira (2) em guia da cidade Praia Grande, no litoral sul de S\u00e3o Paulo. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, um pedreiro de 43 anos e um rapaz, de 19, foram atingidos pelos disparos.<\/p>\n<p>O crime aconteceu no bairro Jardim Gl\u00f3ria. O atirador usava capacete e n\u00e3o foi identificado. Testemunhas disseram \u00e0 pol\u00edcia que o homem parou a moto do outro lado da rua e come\u00e7ou a atirar.<\/p>\n<p>Um rapaz, que mora na regi\u00e3o, foi ferido de rasp\u00e3o na m\u00e3o esquerda. J\u00e1 o pedreiro estava em uma escada colocando azulejos em uma casa e foi atingido na perna e no bra\u00e7o. Os dois receberam atendimentos no Pronto Socorro Central e passam bem.<\/p>\n<p>A pol\u00edcia investiga a hip\u00f3tese de que o atirador tinha como inten\u00e7\u00e3o ferir apenas o rapaz. Segundo o investigador-chefe da 1\u00aa Delegacia de Pol\u00edcia de Praia Grande, Ricardo Mendes, o jovem j\u00e1 tinha passagem pela pol\u00edcia por roubo e saiu da cadeia h\u00e1 dois meses para responder ao processo em liberdade.<\/p>\n<p>Em depoimento, a v\u00edtima disse que n\u00e3o tinha conhecimento de que algu\u00e9m quisesse feri-lo.<\/p>\n<p><strong>HIST\u00d3RICO<\/strong><\/p>\n<p>Uma pessoa morreu e seis pessoas ficaram feridas em uma s\u00e9rie de ataques a pedestres na Baixada Santista na madrugada no dia 10 de abril. Os ataques ocorreram em Santos e S\u00e3o Vicente e foram similares: um homem, em um carro preto, aproximava-se das v\u00edtimas e efetuava os disparos. Um policial militar, suspeito de cometer os ataques, est\u00e1 preso desde o dia 16 de abril.<\/p>\n<p>Outras quatro pessoas foram feridas a tiros enquanto estavam em um pagode no Guaruj\u00e1, tamb\u00e9m no litoral de SP, no dia 30 de abril. Elas foram baleadas por atiradores que estavam em uma moto.<\/p>\n<p>J\u00e1 em 2010, 23 pessoas morreram em uma s\u00e9rie de assassinatos ocorridos em Santos, Guaruj\u00e1, S\u00e3o Vicente e Praia Grande entre 17 e 26 de abril. A s\u00e9rie de assassinatos come\u00e7ou depois da morte de um policial militar no Guaruj\u00e1. Em grande parte desses crimes, a forma de agir foi similar &#8211;motoqueiros se aproximaram da v\u00edtima e dispararam v\u00e1rios tiros. Em outras, dizem testemunhas, os homens estavam em carros de cor escura.<\/p>\n<p><em>Fonte: Folha.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem que estava em uma motocicleta atirou e feriu duas pessoas na tarde de ter\u00e7a-feira (2) em guia da cidade Praia Grande, no litoral sul de S\u00e3o Paulo. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, um pedreiro de 43 anos e um rapaz, de 19, foram atingidos pelos disparos. O crime aconteceu no bairro Jardim Gl\u00f3ria. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"class_list":["post-200","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-praia-grande"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/posts\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=200"}],"version-history":[{"count":2,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/posts\/200\/revisions"}],"predecessor-version":[{"id":1903,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/posts\/200\/revisions\/1903"}],"wp:attachment":[{"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapraiagrande.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}